{"id":1007,"date":"2011-08-01T15:57:09","date_gmt":"2011-08-01T15:57:09","guid":{"rendered":"http:\/\/www.kirchner-immobilienbewertung.de\/blog\/?p=1007"},"modified":"2020-11-19T09:17:03","modified_gmt":"2020-11-19T09:17:03","slug":"hausbesitzer-plus-der-grundsteuer-minus-im-portmonee","status":"publish","type":"post","link":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/hausbesitzer-plus-der-grundsteuer-minus-im-portmonee","title":{"rendered":"Hausbesitzer &#8211; Plus der Grundsteuer = Minus im Portmonee"},"content":{"rendered":"<p style=\"text-align: justify\">Knapp jede dritte gr\u00f6\u00dfere Stadt mit 50.000 oder mehr Einwohnern hat 2011 den Hebesatz der Grundsteuer B f\u00fcr bebaute Grundst\u00fccke erh\u00f6ht. Das geht aus der aktuellen Umfrage des Deutschen Industrie- und Handelskammertags (DIHT) hervor. Die Kommunen freuen sich \u00fcber diese h\u00f6heren Einnahmen durch Immobilienbesitzer. Haus &amp; Grund Deutschland, der Zentralverband der Deutschen Haus-, Wohnungs- und Grundeigent\u00fcmer, ist da schon weniger begeistert.<\/p>\n<h3 style=\"text-align: justify\">Regionale Unterschiede bei der Grundsteuer<\/h3>\n<p style=\"text-align: justify\">Insgesamt haben laut des Deutschen Industrie- und Handelskammertags 32 Prozent der gr\u00f6\u00dferen Gemeinden Deutschland den Hebesatz f\u00fcr die Grundsteuer B erh\u00f6ht. Das sei die st\u00e4rkste Anhebung seit 1992\/1993, schreibt der DIHT weiter. Der durchschnittliche Hebesatz liegt nun statt bei 507 wie im Jahr 2010 bei 517 im Jahr 2011. Berlin besitzt mit 810 Prozent den h\u00f6chsten Hebesatz. 2011 am st\u00e4rksten erh\u00f6ht wurde er jedoch in anderen Kommunen, wie &nbsp;Haus &amp; Grund Deutschland aufzeigt. So stieg der Hebesatz in Stralsund von 420 auf 500 Prozent. Hausbesitzer in Iserlohn werden mit einem Hebesatz von 485 statt zuvor 400 Prozent und in Leverkusen von 590 statt zuvor 500 Prozent konfrontiert. Weitere besonders hohe Anstiege verzeichnen die Kommunen Castrop-Rauxel (von 410 auf 500), Solingen (von 490 auf 590 Prozent) und Leipzig (von 500 auf 650 Prozent).<\/p>\n<h3 style=\"text-align: justify\">Mehraufwand f\u00fcr Hausbesitzer \u2013 ein Rechenbeispiel<\/h3>\n<p style=\"text-align: justify\">Die H\u00f6he der Grundsteuer h\u00e4ngt von drei Faktoren ab: dem Einheitswert, der Steuermesszahl und dem Hebesatz. Legt man einen Einheitswert f\u00fcr ein Grundst\u00fcck mit Zweifamilienhaus von 100.000\u20ac zugrunde, dann liegt die Steuermesszahl laut Grundsteuergesetz bei 3,1 Promille. Das ergibt dann einen Steuermessbetrag von 310\u20ac (3,1 Promille von 10.000\u20ac). Diese Summe wird mit dem Hebesatz der Gemeinden multipliziert, um den Aufwand f\u00fcr den jeweiligen Hausbesitzer zu berechnen. Nimmt man nun den Hebesatz von 500 Prozent f\u00fcr Leipzig aus dem Jahr 2010, so ergeben sich (310\u20ac x 5,0) 1.550\u20ac. Der auf 650 Prozent gestiegene Hebesatz ergibt f\u00fcr 2011 einen Aufwand von 2.015\u20ac und damit einen Mehraufwand pro Jahr von 465\u20ac.<\/p>\n<h3 style=\"text-align: justify\">Die Situation der St\u00e4dte und Gemeinden<\/h3>\n<p style=\"text-align: justify\">Die Finanznot der Kommunen ist dramatisch, zitiert das Magazin \u201eSpiegel\u201c Christian Ude, den Vizepr\u00e4sident des Deutschen St\u00e4dtetags, im November 2010. 2010 habe das Minus der Kommunen bei elf oder zw\u00f6lf Milliarden Euro gelegen, hei\u00dft es weiter. Ein aktueller Gesetzesentwurf, der den Kommunen m\u00f6glicherweise zuk\u00fcnftig die hohen Ausgaben f\u00fcr die Grundsicherung im Alter und bei der Erwerbsminderung erspart, k\u00f6nnte hier deutliche Abhilfe schaffen. Der Deutsche St\u00e4dtetag hat diesen Gesetzentwurf j\u00fcngst in einer offiziellen Stellungnahme grunds\u00e4tzlich begr\u00fc\u00dft. Kurzfristig d\u00fcrfte er finanzielle Probleme der Kommunen jedoch nicht l\u00f6sen. Da sind angehobene Hebes\u00e4tze schon besser: zumindest aus Sicht der Kommunen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Knapp jede dritte gr\u00f6\u00dfere Stadt mit 50.000 oder mehr Einwohnern hat 2011 den Hebesatz der Grundsteuer B f\u00fcr bebaute Grundst\u00fccke erh\u00f6ht. Das geht aus der aktuellen Umfrage des Deutschen Industrie- und Handelskammertags (DIHT) hervor. Die Kommunen freuen sich \u00fcber diese h\u00f6heren Einnahmen durch Immobilienbesitzer. Haus &amp; Grund Deutschland, der Zentralverband der Deutschen Haus-, Wohnungs- und [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[1,14],"tags":[1165,1164,1163,233,451,1166],"class_list":["post-1007","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-immobilien-allgemein","category-wohnimmobilien","tag-deutscher-industrie-und-handelskammertag","tag-deutscher-stadtetag","tag-diht","tag-grundsteuer","tag-hebesatz","tag-hebesatze","entry","has-media"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/1007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/comments?post=1007"}],"version-history":[{"count":3,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/1007\/revisions"}],"predecessor-version":[{"id":2538,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/1007\/revisions\/2538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/media\/2537"}],"wp:attachment":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/media?parent=1007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/categories?post=1007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/tags?post=1007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}