{"id":291,"date":"2010-07-28T21:10:27","date_gmt":"2010-07-28T21:10:27","guid":{"rendered":"http:\/\/www.kirchner-immobilienbewertung.de\/blog\/?p=291"},"modified":"2020-11-19T15:22:36","modified_gmt":"2020-11-19T15:22:36","slug":"immopionier-neue-meta-immobiliensuche-im-internet","status":"publish","type":"post","link":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/immopionier-neue-meta-immobiliensuche-im-internet","title":{"rendered":"ImmoPionier \u2013 neue Meta-Immobiliensuche im Internet"},"content":{"rendered":"<p style=\"text-align: justify\">\u201eImmoPionier.de\u201c hei\u00dft eine neue Immobilien-Metasuchmaschine im Internet. Ins Netz gesetzt wurde sie von der neu gegr\u00fcndeten InterfaceOne GmbH der drei ehemaligen Informatikstudenten Till Aust, Malte Sarnow und Christian Sp\u00e4h von der Universit\u00e4t Hamburg. Derzeit zeigt die Suchmaschine Immobilienangebote der Portale Immonet, ImmobilienScout24 und immowelt an. Ergebnisse weiterer Immobilienportale sollen in Zukunft ebenfalls in die Meta-Suchmaschine integriert werden.<\/p>\n<h3 style=\"text-align: justify\"><strong>Was bietet ImmoPionier.de?<\/strong><\/h3>\n<p style=\"text-align: justify\">ImmoPionier.de entfernt bei Suchanfragen von Nutzern Duplikate, also gleiche Immobilienangebote von verschiedenen Portalen, um den Nutzern die Recherche nach passenden Immobilien zu vereinfachen. Suchende k\u00f6nnen f\u00fcr sie interessante Immobilien zudem in einer Merkliste speichern und andererseits Immobilienangebote, die f\u00fcr sie nicht tauglich erscheinen, f\u00fcr die Zukunft blockieren. Auch Suchanfragen lassen sich speichern, um in regelm\u00e4\u00dfigen Abst\u00e4nden wiederholt zu werden. F\u00fcr die Suche hat man die Auswahl zwischen Wohn-, Gewerbe- und Anlageimmobilien zum Kaufen oder Mieten. Abfragen, die gesuchte Immobilien weiter eingrenzen, sind die Anzahl der Zimmer, die Gr\u00f6\u00dfe der Immobilie und der gew\u00fcnschte Miet- beziehungsweise Kaufpreis. Hier k\u00f6nnen jeweils Minimal- und Maximalwerte eingegeben werden. Bei Wohnimmobilien wie bei Anlageimmobilien k\u00f6nnen Nutzer zudem angeben, ob sie eine Wohnung oder ein Haus suchen. Bei Gewerbeimmobilien stehen Garagen und Grundst\u00fccke zur Auswahl. Die Ergebnisliste zeigt dem Nutzer sofort, wie viele Immobilienangebote sie enth\u00e4lt; grundlegende Informationen zum Immobilienangebot findet man bereits in der Suchmaschine. Ein Mausklick bringt den Nutzer dann zur detaillierten Beschreibung auf dem jeweiligen Portal.<\/p>\n<h3 style=\"text-align: justify\"><strong>Suche auch \u00fcber Karte m\u00f6glich<\/strong><\/h3>\n<p style=\"text-align: justify\">Eine besondere Spezialit\u00e4t von ImmoPionier.de ist die Suche \u00fcber eine in die Suchmaschine integrierte Karte. Durch sie k\u00f6nnen Nutzer den Suchbereich f\u00fcr ihre neue Immobilie schnell regional eingrenzen und auf Wunsch auch um Nachbarregionen erweitern. So lassen sich alle Immobilien in Regionen anzeigen, die f\u00fcrs neue Zuhause in Frage kommen. Mit seinem Angebot konkurriert die neue Suchmaschine ImmoPionier beispielsweise mit der bereits l\u00e4nger bestehenden Immobilien-Suchmaschine Immobilo. Die Betreiber von ImmoPionier.de wollen hier durch eine verbesserte Linkg\u00fcte sowie die bereits erw\u00e4hnte Navigation \u00fcber die Karte punkten. Die Finanzierung des Projekts erfolgt ausschlie\u00dflich \u00fcber Werbung und nicht durch eine direkte Kooperation mit den f\u00fcr die Suche genutzten Immobilienportalen. Die Suchmaschine pr\u00e4sentiert \u201enur\u201c die Angebote der jeweiligen Portale. Es bleibt abzuwarten, ob sich ImmoPionier.de auf dem deutschen Markt f\u00fcr Immobilien-Suchmaschinen durchsetzt. Ein Test der Suchmaschine kann jedenfalls nicht schaden.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201eImmoPionier.de\u201c hei\u00dft eine neue Immobilien-Metasuchmaschine im Internet. Ins Netz gesetzt wurde sie von der neu gegr\u00fcndeten InterfaceOne GmbH der drei ehemaligen Informatikstudenten Till Aust, Malte Sarnow und Christian Sp\u00e4h von der Universit\u00e4t Hamburg. Derzeit zeigt die Suchmaschine Immobilienangebote der Portale Immonet, ImmobilienScout24 und immowelt an. Ergebnisse weiterer Immobilienportale sollen in Zukunft ebenfalls in die Meta-Suchmaschine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[13,1,14],"tags":[389,384,388,383,386,387,385,391,390],"class_list":["post-291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gewerbeimmobilien","category-immobilien-allgemein","category-wohnimmobilien","tag-immobilien-suchmaschine","tag-immobilienscout24","tag-immobiliensuchmaschine","tag-immonet","tag-immopionier","tag-immopionier-de","tag-immowelt","tag-interfaceone-gmbh","tag-metasuchmaschine-immobilien","entry","has-media"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":4,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/291\/revisions"}],"predecessor-version":[{"id":2817,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/291\/revisions\/2817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/media\/2816"}],"wp:attachment":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/media?parent=291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/categories?post=291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/tags?post=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}