{"id":326,"date":"2010-08-13T13:43:02","date_gmt":"2010-08-13T13:43:02","guid":{"rendered":"http:\/\/www.kirchner-immobilienbewertung.de\/blog\/?p=326"},"modified":"2020-11-19T15:05:11","modified_gmt":"2020-11-19T15:05:11","slug":"bundesfinanzhof-und-einheitswert-wohin-steuert-die-grundsteuer","status":"publish","type":"post","link":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/bundesfinanzhof-und-einheitswert-wohin-steuert-die-grundsteuer","title":{"rendered":"Bundesfinanzhof \u2013 wohin steuert die Grundsteuer?"},"content":{"rendered":"<p style=\"text-align: justify\">1964 bekam Martin Luther King den Friedensnobelpreis. Der afrikanische Staat Malawi wurde unabh\u00e4ngig und die Deutsche Bundesbank gab die ersten 1000-Mark-Scheine heraus. 1964 wurden auch Einheitswerte f\u00fcr die Grundsteuer ermittelt, die in Westdeutschland bis heute gelten. In Ostdeutschland geht man gar nach wie vor von Werten aus dem Jahr 1935 aus. Mittlerweile schreiben wir das Jahr 2010. 46 Jahre oder gar 75 Jahre sind eine lange Zeit. Dennoch entschied der Bundesfinanzhof nun in einem aktuellen Fall, dass die alten erhobenen Werte in Deutschland zumindest bis zum Beginn des Jahres 2007 angewendet werden k\u00f6nnen. Allerdings mahnt er dringend eine neue Festlegung der Einheitswerte an. Steigt die Grundsteuer dadurch?<\/p>\n<h3 style=\"text-align: justify\"><strong>Grundlegendes zur Grundsteuer<\/strong><\/h3>\n<p style=\"text-align: justify\">Beginnen wir mit Grundlegendem: Der vom Finanzamt festgelegte Einheitswert ist eine Komponente bei der Berechnung der Grundsteuer. Die Grundsteuermesszahl ist wiederum ein Promillesatz des Einheitswertes. Mit ihr wird dann der Grundsteuermessbetrag berechnet. Ein Beispiel: Die Grundsteuermesszahl betr\u00e4gt etwa bei Mehrfamilienh\u00e4usern 3,5 Promille. Nehmen wir an, der Einheitswert liegt bei 200.000 Euro und wird f\u00fcr ein Mehrfamilienhaus mit einer Grundsteuermesszahl von 3,5 Promille multipliziert. Das ergibt dann einen Wert von 700 Euro. Dieser Wert wird anschlie\u00dfend noch mit dem von der jeweiligen Gemeinde festgelegten Hebesatz multipliziert. Dieser Hebesatz ist unterschiedlich hoch und kann beispielsweise 3,5 betragen. Als festgelegte Grundsteuer ergeben sich dann in unserem Beispiel (3,5 x 700) 2.940 Euro pro Jahr. Diese Summe zahlt der Hausbesitzer. Bei Mietsh\u00e4usern sind in der Regel die Mieter die Zahlenden, auf die die Kosten umgelegt werden.<\/p>\n<h3 style=\"text-align: justify\"><strong>Neue Daten braucht das System<\/strong><\/h3>\n<p style=\"text-align: justify\">Der Einheitswert ist also die Grundlage der weiteren Berechnung f\u00fcr die Grundsteuer. Wird er anhand von Daten und Normbauweisen aus dem Jahr 1964 vom Finanzamt ermittelt, hat er mit der heutigen Realit\u00e4t oftmals nichts zu tun. Normalerweise sollen die Daten alle sechs Jahre neu festgelegt werden, was allerdings seit 1964 nicht mehr geschehen ist. \u201eDas System stimme nicht mehr\u201c, urteilte deshalb Michael Wendt, der Pressesprecher des Bundesfinanzhofes. M\u00f6glicherweise scheuen die Beh\u00f6rden allerdings den immensen Aufwand bei der Erhebung neuer Daten. Zehn Jahre lang soll es gedauert haben, bis die letzte Datenerhebung abgeschlossen war. Heute w\u00fcrde das Procedere wohl etwas schneller ablaufen, aber auch keinesfalls in k\u00fcrzester Zeit. Dennoch wird man um neue Daten f\u00fcr den Einheitswert nicht herumkommen: Aufgrund der veralteten Daten gibt es heute \u00fcber- und andererseits auch unterbewertete Immobilien. Mit dem Verkehrswert einer Immobilie hat der Einheitswert jedenfalls in den wenigsten F\u00e4llen etwas gemeinsam.<\/p>\n<h3 style=\"text-align: justify\"><strong>Wird die Grundsteuer angehoben?<\/strong><\/h3>\n<p style=\"text-align: justify\">Die Basis der Grundsteuer-Berechnung ist seit Jahren in der Kritik. Einer aufkeimenden Furcht vor einer nach Daten-Neuerhebung deutlich ansteigenden Grundsteuer versuchte Michael Wendt entgegenzusteuern. Falls sich der Einheitswert eventuell am Marktwert einer Immobilie orientiere, w\u00fcrde er h\u00e4ufig ansteigen. Die Kommunen w\u00fcrden allerdings, so Wendt, voraussichtlich mit einer Absenkung ihres Hebesatzes reagieren, um die Folgen f\u00fcr Hausbesitzer und Mieter in Grenzen zu halten. Fraglich bleibt jedoch, ob sich die Kommunen solch eine Chance f\u00fcr steigende Einnahmen komplett entgehen lassen: Schlie\u00dflich sind viele Stadt- und Gemeindekassen nicht zum Bersten gef\u00fcllt.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>1964 bekam Martin Luther King den Friedensnobelpreis. Der afrikanische Staat Malawi wurde unabh\u00e4ngig und die Deutsche Bundesbank gab die ersten 1000-Mark-Scheine heraus. 1964 wurden auch Einheitswerte f\u00fcr die Grundsteuer ermittelt, die in Westdeutschland bis heute gelten. In Ostdeutschland geht man gar nach wie vor von Werten aus dem Jahr 1935 aus. Mittlerweile schreiben wir das [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2800,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[13,1,14],"tags":[449,450,452,233,456,454,451,235,455,453],"class_list":["post-326","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gewerbeimmobilien","category-immobilien-allgemein","category-wohnimmobilien","tag-bundesfinanzhof","tag-einheitswert","tag-einnahmen","tag-grundsteuer","tag-grundsteuerbetrag","tag-grundsteuermesszahl","tag-hebesatz","tag-kommunen","tag-messzahl","tag-michael-wendt","entry","has-media"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/326","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/comments?post=326"}],"version-history":[{"count":4,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/326\/revisions"}],"predecessor-version":[{"id":2801,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/posts\/326\/revisions\/2801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/media\/2800"}],"wp:attachment":[{"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/media?parent=326"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/categories?post=326"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.kirchner-immobilienbewertung.de\/blog\/wp-json\/wp\/v2\/tags?post=326"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}